{"id":74874,"date":"2026-05-28T21:51:16","date_gmt":"2026-05-28T21:51:16","guid":{"rendered":"https:\/\/ezu.com.br\/lojas\/2026\/05\/comoda-modulo-inferior-1-porta-requinte-100-mdf-macadamia-duna-line\/"},"modified":"2026-05-28T21:51:16","modified_gmt":"2026-05-28T21:51:16","slug":"comoda-modulo-inferior-1-porta-requinte-100-mdf-macadamia-duna-line","status":"publish","type":"post","link":"https:\/\/ezu.com.br\/lojas\/2026\/05\/comoda-modulo-inferior-1-porta-requinte-100-mdf-macadamia-duna-line\/","title":{"rendered":"C\u00f4moda M\u00f3dulo Inferior 1 Porta Requinte 100% MDF Macad\u00e2mia\/Duna Line"},"content":{"rendered":"<h2><\/h2>\n<h3>O pre\u00e7o de C\u00f4moda M\u00f3dulo Inferior 1 Porta Requinte 100% MDF Macad\u00e2mia\/Duna Line nas lojas online, no dia acima, era aproximadamente <strong>R$ BRL418.73<\/strong>. Para informa\u00e7\u00f5es atualizadas, acesse este produto em dezenas de lojas dos marketplaces do Sistema Magalu:<\/h3>\n<p><a href=\"https:\/\/www.magazinevoce.com.br\/magazineezu\/busca\/C\u00f4moda M\u00f3dulo Inferior 1 Porta Requinte 100% MDF Macad\u00e2mia\/Duna Line\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/casatema.vteximg.com.br\/arquivos\/ids\/856635_2\" alt=\"C\u00f4moda M\u00f3dulo Inferior 1 Porta Requinte 100% MDF Macad\u00e2mia\/Duna Line\" \/> &#8211; CLIQUE AQUI<\/a>.<br \/>\nC\u00f4moda M\u00f3dulo Inferior 1 Porta Requinte 100% MDF Macad\u00e2mia\/Duna Line  .body-casatema-use-internal { font-family: Arial, sans-serif; line-height: 1.6; } .container-casatema-use-internal { width: 80%; margin: 0 auto; padding: 20px; } .hx-casatema-use-internal { color: #333; } .ul-casatema-use-internal { list-style-type: none; padding: 0; } .li-casatema-use-internal { background: #f4f4f4; margin: 5px 0; padding: 10px; border-radius: 5px; } .highlight-casatema-use-internal { font-weight: bold; } .image-container-casatema-use-internal, .img-casatema-use-internal { width: 100%; height: auto; } \/* CSS para os atributos *\/ .table-attr-casatema-use-internal { border-spacing: 0px; width: 100%; } .table-attr-casatema-use-internal tr:nth-child(even) { background: #ffffff; } .table-attr-casatema-use-internal tr:nth-child(odd) { background: #dfede9; } .td-left-attr-casatema-use-internal { padding: 10px; width: 30%; font-weight: bold; } .td-right-attr-casatema-use-internal { padding: 10px; width: 70%; } .div-left-attr-casatema-use-internal { width: 100%; } .div-right-attr-casatema-use-internal { width: 100%; } .div-group-attr-casatema-use-internal { padding-bottom: 10px; } @media (min-width: 1224px) { .div-left-attr-casatema-use-internal { width: 49%; float: left; } .div-right-attr-casatema-use-internal { width: 49%; float: right; } }     C\u00f4moda M\u00f3dulo Inferior 1 Porta Requinte 100% MDF Macad\u00e2mia\/Duna Line. A Linha Requinte da M\u00f3veis Castro oferece um amplo espa\u00e7o e perfeita distribui\u00e7\u00e3o interna, al\u00e9m de agregar beleza e sofistica\u00e7\u00e3o ao seu ambiente. Este produto \u00e9 produzido em chapas de 100% MDF e traz toda comodidade, qualidade e conforto que voc\u00ea precisa no seu dia a dia.   Caracter\u00edsticasAmbiente PrincipalQuartoCorMacad\u00e2mia\/Duna LineCor PredominanteMarromCor do ProdutoMacad\u00e2mia\/Duna LineEstiloModernoInforma\u00e7\u00f5es Complementares (Novo)Porta c\/montagem direita\/esquerdaLinha ou Cole\u00e7\u00e3oRequinteMarcaM\u00f3veis CastroModularSimOrigem do ProdutoNacionalPeso M\u00e1ximo por Prateleira5.0Tipo de Guarda-roupaModuladoOutras caracter\u00edsticasCorMacad\u00e2mia\/Duna LinePesos e Dimens\u00f5esAltura (cm)80.5Espessura da Estrutura (mm)15.0Espessura das Portas (mm)15.0Espessura do Fundo (mm)3.0Espessura do Fundo das Gavetas (mm)3.0Largura (cm)50.0Peso (kg)21.4Profundidade (cm)45.0Documentos AdicionaisManual de Montagem e Instala\u00e7\u00e3oClique aqui para acessarGarantiaGarantia03 MesesItens InclusosItens Inclusos1 M\u00f3dulo, Kit Ferragens e Manual de MontagemMateriais e AcabamentosAcabamentoPintura UVEscala de BrilhoSemi-FoscoMaterial PrincipalMDFMontagemComplexidade da MontagemM\u00e9dia: pode ser montado por mais de uma pessoa e\/ou necessite de maior conhecimento para montagemNecessita MontagemSimRecomenda\u00e7\u00f5es de Uso, Manuten\u00e7\u00e3o e LimpezaLimpeza com pano umedecido.Sistema de MontagemParafusos.<\/p>\n<p>345270610734255216077034432552166107<\/p>\n<hr \/>\n<p>Ainda n\u00e3o encontrou a melhor op\u00e7\u00e3o de compra? Oferecemos mais uma possibilidade de <strong>busca<\/strong> mais ampla para <a href=\"https:\/\/ecompare.com.br\/lojas\/resultados-da-pesquisa\/?q=C\u00f4moda M\u00f3dulo Inferior 1 Porta Requinte 100% MDF Macad\u00e2mia\/Duna Line#gsc.tab=0&amp;gsc.q=C\u00f4moda M\u00f3dulo Inferior 1 Porta Requinte 100% MDF Macad\u00e2mia\/Duna Line&amp;gsc.page=1\" target=\"_blank\" rel=\"noopener\">C\u00f4moda M\u00f3dulo Inferior 1 Porta Requinte 100% MDF Macad\u00e2mia\/Duna Line, clique e continue <strong>pesquisando&#8230;<\/strong><\/a><\/p>\n<hr \/>\n","protected":false},"excerpt":{"rendered":"<p>R$ 418.73 nas lojas <a href=\"https:\/\/www.awin1.com\/pclick.php?p=38605493764&#038;a=690303&#038;m=100453\" target=\"_blank\" rel=\"sponsored\">Casa Tema BR<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[7568,7432],"class_list":["post-74874","post","type-post","status-publish","format-standard","hentry","category-produtos","tag-418-73","tag-casa-tema-br"],"_links":{"self":[{"href":"https:\/\/ezu.com.br\/lojas\/wp-json\/wp\/v2\/posts\/74874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ezu.com.br\/lojas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ezu.com.br\/lojas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ezu.com.br\/lojas\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ezu.com.br\/lojas\/wp-json\/wp\/v2\/comments?post=74874"}],"version-history":[{"count":0,"href":"https:\/\/ezu.com.br\/lojas\/wp-json\/wp\/v2\/posts\/74874\/revisions"}],"wp:attachment":[{"href":"https:\/\/ezu.com.br\/lojas\/wp-json\/wp\/v2\/media?parent=74874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ezu.com.br\/lojas\/wp-json\/wp\/v2\/categories?post=74874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ezu.com.br\/lojas\/wp-json\/wp\/v2\/tags?post=74874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}