{"id":47156,"date":"2026-06-19T05:41:35","date_gmt":"2026-06-19T05:41:35","guid":{"rendered":"https:\/\/ezu.com.br\/lojas\/2026\/06\/placa-de-controle-bivolt-para-cervejeira-consul-w10603639-w10603639\/"},"modified":"2026-06-19T05:41:35","modified_gmt":"2026-06-19T05:41:35","slug":"placa-de-controle-bivolt-para-cervejeira-consul-w10603639-w10603639","status":"publish","type":"post","link":"https:\/\/ezu.com.br\/lojas\/2026\/06\/placa-de-controle-bivolt-para-cervejeira-consul-w10603639-w10603639\/","title":{"rendered":"Placa De Controle Bivolt Para Cervejeira Consul &#8211; W10603639 W10603639"},"content":{"rendered":"<h2><\/h2>\n<h3>O pre\u00e7o de Placa De Controle Bivolt Para Cervejeira Consul &#8211; W10603639 W10603639 nas lojas online, no dia acima, era aproximadamente <strong>R$ BRL330.9<\/strong>. Para informa\u00e7\u00f5es atualizadas, acesse este produto em dezenas de lojas dos marketplaces do Sistema Magalu:<\/h3>\n<p><a href=\"https:\/\/www.magazinevoce.com.br\/magazineezu\/busca\/Placa De Controle Bivolt Para Cervejeira Consul - W10603639 W10603639\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/whirlpool.vteximg.com.br\/arquivos\/ids\/202571\/W10603639_01.jpg?v=637045138867630000\" alt=\"Placa De Controle Bivolt Para Cervejeira Consul - W10603639 W10603639\" \/> &#8211; CLIQUE AQUI<\/a>.<br \/>\nA placa de controle para cervejeira \u00e9 respons\u00e1vel pelo controle de a\u00e7\u00f5es como ajustes de temperatura, ventila\u00e7\u00e3o e funcionamento do motor al\u00e9m de ser encarregada de fazer a distribui\u00e7\u00e3o de energia para os outros componentes.<\/p>\n<p>345270610734255216077034432552166107<\/p>\n<hr \/>\n<p>Ainda n\u00e3o encontrou a melhor op\u00e7\u00e3o de compra? Oferecemos mais uma possibilidade de <strong>busca<\/strong> mais ampla para <a href=\"https:\/\/ecompare.com.br\/lojas\/resultados-da-pesquisa\/?q=Placa De Controle Bivolt Para Cervejeira Consul - W10603639 W10603639#gsc.tab=0&amp;gsc.q=Placa De Controle Bivolt Para Cervejeira Consul - W10603639 W10603639&amp;gsc.page=1\" target=\"_blank\" rel=\"noopener\">Placa De Controle Bivolt Para Cervejeira Consul &#8211; W10603639 W10603639, clique e continue <strong>pesquisando&#8230;<\/strong><\/a><\/p>\n<hr \/>\n","protected":false},"excerpt":{"rendered":"<p>R$ 330.9 nas lojas <a href=\"https:\/\/www.awin1.com\/pclick.php?p=43709137629&#038;a=690303&#038;m=17639\" target=\"_blank\" rel=\"sponsored\">Consul BR<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[2580,2704],"class_list":["post-47156","post","type-post","status-publish","format-standard","hentry","category-produtos","tag-330-9","tag-consul-br"],"_links":{"self":[{"href":"https:\/\/ezu.com.br\/lojas\/wp-json\/wp\/v2\/posts\/47156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ezu.com.br\/lojas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ezu.com.br\/lojas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ezu.com.br\/lojas\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ezu.com.br\/lojas\/wp-json\/wp\/v2\/comments?post=47156"}],"version-history":[{"count":0,"href":"https:\/\/ezu.com.br\/lojas\/wp-json\/wp\/v2\/posts\/47156\/revisions"}],"wp:attachment":[{"href":"https:\/\/ezu.com.br\/lojas\/wp-json\/wp\/v2\/media?parent=47156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ezu.com.br\/lojas\/wp-json\/wp\/v2\/categories?post=47156"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ezu.com.br\/lojas\/wp-json\/wp\/v2\/tags?post=47156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}