{"id":46696,"date":"2026-05-17T03:59:21","date_gmt":"2026-05-17T03:59:21","guid":{"rendered":"https:\/\/ezu.com.br\/lojas\/2026\/05\/frigobar-brastemp-retro-76-litros-classic-red-bra08mv-220v\/"},"modified":"2026-05-17T03:59:21","modified_gmt":"2026-05-17T03:59:21","slug":"frigobar-brastemp-retro-76-litros-classic-red-bra08mv-220v","status":"publish","type":"post","link":"https:\/\/ezu.com.br\/lojas\/2026\/05\/frigobar-brastemp-retro-76-litros-classic-red-bra08mv-220v\/","title":{"rendered":"Frigobar Brastemp Retr\u00f4 76 Litros Classic Red &#8211; Bra08mv 220V"},"content":{"rendered":"<h2><\/h2>\n<h3>O pre\u00e7o de Frigobar Brastemp Retr\u00f4 76 Litros Classic Red &#8211; Bra08mv 220V nas lojas online, no dia acima, era aproximadamente <strong>R$ BRL2088.36<\/strong>. Para informa\u00e7\u00f5es atualizadas, acesse este produto em dezenas de lojas dos marketplaces do Sistema Magalu:<\/h3>\n<p><a href=\"https:\/\/www.magazinevoce.com.br\/magazineezu\/busca\/Frigobar Brastemp Retr\u00f4 76 Litros Classic Red - Bra08mv 220V\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/whirlpool.vteximg.com.br\/arquivos\/ids\/279446\/01_Brastemp_Frigobar_Compactos_BRA08MV.jpg?v=639075544477900000\" alt=\"Frigobar Brastemp Retr\u00f4 76 Litros Classic Red - Bra08mv 220V\" \/> &#8211; CLIQUE AQUI<\/a>.<br \/>\nO frigobar brastemp retr\u00f4 76 litros com performance de refrigera\u00e7\u00e3o eficiente que economiza at\u00e9 21% de energia el\u00e9trica no ano[1], transforma qualquer ambiente no seu mundo! o design inconfund\u00edvel conta com os acabamentos vintage com p\u00e9s palito, puxadores met\u00e1licos e o ic\u00f4nico logo brastemp dos anos 50. em 8 op\u00e7\u00f5es de cores exclusivas, sejam as cl\u00e1ssicas ou as inspiradas nas tend\u00eancias mais atuais do design, pra voc\u00ea escolher a que representa melhor o seu estilo. al\u00e9m disso, se surpreenda com a possibilidade de armazenar tudo como voc\u00ea quiser, seja com os compartimentos modulares, cesto cromado ou no freezer &#8211; que d\u00e1 um gelo em qualquer frigobar.<\/p>\n<p>345270610734255216077034432552166107<\/p>\n<hr \/>\n<p>Ainda n\u00e3o encontrou a melhor op\u00e7\u00e3o de compra? Oferecemos mais uma possibilidade de <strong>busca<\/strong> mais ampla para <a href=\"https:\/\/ecompare.com.br\/lojas\/resultados-da-pesquisa\/?q=Frigobar Brastemp Retr\u00f4 76 Litros Classic Red - Bra08mv 220V#gsc.tab=0&amp;gsc.q=Frigobar Brastemp Retr\u00f4 76 Litros Classic Red - Bra08mv 220V&amp;gsc.page=1\" target=\"_blank\" rel=\"noopener\">Frigobar Brastemp Retr\u00f4 76 Litros Classic Red &#8211; Bra08mv 220V, clique e continue <strong>pesquisando&#8230;<\/strong><\/a><\/p>\n<hr \/>\n","protected":false},"excerpt":{"rendered":"<p>R$ 2088.36 nas lojas <a href=\"https:\/\/www.awin1.com\/pclick.php?p=44123027568&#038;a=690303&#038;m=17772\" target=\"_blank\" rel=\"sponsored\">Brastemp BR<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[2674,1493],"class_list":["post-46696","post","type-post","status-publish","format-standard","hentry","category-produtos","tag-2088-36","tag-brastemp-br"],"_links":{"self":[{"href":"https:\/\/ezu.com.br\/lojas\/wp-json\/wp\/v2\/posts\/46696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ezu.com.br\/lojas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ezu.com.br\/lojas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ezu.com.br\/lojas\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ezu.com.br\/lojas\/wp-json\/wp\/v2\/comments?post=46696"}],"version-history":[{"count":0,"href":"https:\/\/ezu.com.br\/lojas\/wp-json\/wp\/v2\/posts\/46696\/revisions"}],"wp:attachment":[{"href":"https:\/\/ezu.com.br\/lojas\/wp-json\/wp\/v2\/media?parent=46696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ezu.com.br\/lojas\/wp-json\/wp\/v2\/categories?post=46696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ezu.com.br\/lojas\/wp-json\/wp\/v2\/tags?post=46696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}