{"id":37510,"date":"2026-05-10T21:41:12","date_gmt":"2026-05-10T21:41:12","guid":{"rendered":"https:\/\/ezu.com.br\/lojas\/2026\/05\/calca-bordada-preto-38\/"},"modified":"2026-05-10T21:41:12","modified_gmt":"2026-05-10T21:41:12","slug":"calca-bordada-preto-38","status":"publish","type":"post","link":"https:\/\/ezu.com.br\/lojas\/2026\/05\/calca-bordada-preto-38\/","title":{"rendered":"Cal\u00e7a Bordada Preto &#8211; 38"},"content":{"rendered":"<h2>BAZAR &#8211; CAL\u00c7A<\/h2>\n<h3>O pre\u00e7o de Cal\u00e7a Bordada Preto &#8211; 38 nas lojas online, no dia acima, era aproximadamente <strong>R$ BRL1879.00<\/strong>. Para informa\u00e7\u00f5es atualizadas, acesse este produto em dezenas de lojas dos marketplaces do Sistema Magalu:<\/h3>\n<p><a href=\"https:\/\/www.magazinevoce.com.br\/magazineezu\/busca\/Cal\u00e7a Bordada Preto - 38\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/lojaanimale.vteximg.com.br\/arquivos\/ids\/1625074_2\" alt=\"Cal\u00e7a Bordada Preto - 38\" \/> &#8211; CLIQUE AQUI<\/a>.<br \/>\n&#8211; Cal\u00e7a Bordada Preto &#8211; 38<\/p>\n<p>345270610734255216077034432552166107<\/p>\n<hr \/>\n<p>Ainda n\u00e3o encontrou a melhor op\u00e7\u00e3o de compra? Oferecemos mais uma possibilidade de <strong>busca<\/strong> mais ampla para <a href=\"https:\/\/ecompare.com.br\/lojas\/resultados-da-pesquisa\/?q=Cal\u00e7a Bordada Preto - 38#gsc.tab=0&amp;gsc.q=Cal\u00e7a Bordada Preto - 38&amp;gsc.page=1\" target=\"_blank\" rel=\"noopener\">Cal\u00e7a Bordada Preto &#8211; 38, clique e continue <strong>pesquisando&#8230;<\/strong><\/a><\/p>\n<hr \/>\n","protected":false},"excerpt":{"rendered":"<p>R$ 1879.00 nas lojas <a href=\"https:\/\/www.awin1.com\/pclick.php?p=42804225512&#038;a=690303&#038;m=104715\" target=\"_blank\" rel=\"sponsored\">Animale BR<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[1199,969,1179],"class_list":["post-37510","post","type-post","status-publish","format-standard","hentry","category-produtos","tag-1879-00","tag-animale-br","tag-bazar-calca"],"_links":{"self":[{"href":"https:\/\/ezu.com.br\/lojas\/wp-json\/wp\/v2\/posts\/37510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ezu.com.br\/lojas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ezu.com.br\/lojas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ezu.com.br\/lojas\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ezu.com.br\/lojas\/wp-json\/wp\/v2\/comments?post=37510"}],"version-history":[{"count":0,"href":"https:\/\/ezu.com.br\/lojas\/wp-json\/wp\/v2\/posts\/37510\/revisions"}],"wp:attachment":[{"href":"https:\/\/ezu.com.br\/lojas\/wp-json\/wp\/v2\/media?parent=37510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ezu.com.br\/lojas\/wp-json\/wp\/v2\/categories?post=37510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ezu.com.br\/lojas\/wp-json\/wp\/v2\/tags?post=37510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}